{"id":10273,"date":"2023-07-24T12:30:27","date_gmt":"2023-07-24T05:30:27","guid":{"rendered":"https:\/\/il.mahidol.ac.th\/eng\/?p=10273"},"modified":"2023-07-25T15:03:54","modified_gmt":"2023-07-25T08:03:54","slug":"workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023","status":"publish","type":"post","link":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/","title":{"rendered":"Workshop on STEM &amp; Robotics Camp,Suratthani School,  July 22-23, 2023."},"content":{"rendered":"<p>Dr. Tinnaphop Phengpom, Mr. Pongpatai Kitrungloadjanaporn and Mr. Putcharasit Pejaroend, Institute for Innovative Learning, Mahidol University organized <strong>a STEM &amp; Robotics Camp workshop <\/strong>on the &#8220;Science Day Camp Activity&#8221; for Grade 8 students on July 22, 2023 and organized &#8220;STEM Junior Camp Activity&#8221; on July 23, 2023 for Grade 7 students at Lam Yong Teachers&#8217; Auditorium, Suratthani School, Suratthani Province.<\/p>\n<div id='gallery-1' class='gallery galleryid-10273 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-049.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-049.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-049.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-049-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-050.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-050.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-050.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-050-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-061.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-061.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-061.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-061-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-062.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-062.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-062.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-062-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-053.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-053.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-053.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-053-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-054.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-054.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-054.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-054-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-055.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-055.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-055.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-055-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-051.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-051.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-051.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-051-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-052.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-052.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-052.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-052-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-056.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-056.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-056.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-056-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-057.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-057.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-057.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-057-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-058.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-058.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-058.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-058-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-059.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-059.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-059.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-059-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-060.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-060.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-060.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-060-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-002.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-002.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-002.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-002-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-003.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-003.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-003.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-003-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-004.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-004.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-004.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-004-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-005.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-005.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-005.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-005-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-006.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-006.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-006.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-006-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-007.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-007.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-007.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-007-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-008.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-008.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-008.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-008-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-009.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-009.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-009.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-009-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-010.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-010.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-010.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-010-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-011.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-011.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-011.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-011-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-012.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-012.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-012.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-012-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-013.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-013.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-013.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-013-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-015.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-015.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-015.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-015-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-016.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-016.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-016.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-016-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-014.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-014.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-014.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-014-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-017.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-017.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-017.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-017-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-018.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-018.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-018.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-018-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-019.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-019.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-019.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-019-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-020.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-020.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-020.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-020-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-021.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-021.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-021.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-021-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-022.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-022.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-022.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-022-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-023.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-023.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-023.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-023-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-024.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-024.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-024-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-025.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-025.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-025.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-025-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-026.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-026.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-026.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-026-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-027.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-027.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-027.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-027-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-028.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-028.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-028.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-028-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-029.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-029.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-029.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-029-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-030.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-030.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-030.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-030-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-031.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-031.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-031.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-031-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-032.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-032.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-032.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-032-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-033.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-033.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-033.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-033-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-034.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-034.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-034.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-034-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-035.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-035.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-035.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-035-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-036.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-036.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-036.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-036-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-037.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-037.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-037.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-037-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-039.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-039.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-039.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-039-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-040.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-040.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-040.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-040-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-038.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-038.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-038.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-038-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-041.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-041.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-041.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-041-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-042.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-042.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-042.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-042-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-043.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-043.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-043.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-043-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-044.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-044.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-044.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-044-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-045.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-045.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-045.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-045-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-046.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-046.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-046.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-046-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-047.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-047.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-047.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-047-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-048.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-048.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-048.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-048-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Dr. Tinnaphop Phengpom, Mr. Pongpatai Kitrungloadjanapo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":10347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[109,110,472],"class_list":["post-10273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academic-services","tag-institute-for-innovative-learning","tag-mahidol-university","tag-suratthani-school"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning\" \/>\n<meta property=\"og:description\" content=\"Dr. Tinnaphop Phengpom, Mr. Pongpatai Kitrungloadjanapo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Institute for Innovative Learning\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-24T05:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T08:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"IL PR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/\"},\"author\":{\"name\":\"IL PR News\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\"},\"headline\":\"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023.\",\"datePublished\":\"2023-07-24T05:30:27+00:00\",\"dateModified\":\"2023-07-25T08:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/\"},\"wordCount\":68,\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\",\"keywords\":[\"institute for innovative learning\",\"mahidol university\",\"Suratthani School\"],\"articleSection\":[\"academic services\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/\",\"name\":\"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\",\"datePublished\":\"2023-07-24T05:30:27+00:00\",\"dateModified\":\"2023-07-25T08:03:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\",\"contentUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/\",\"name\":\"Institute for Innovative Learning\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\",\"name\":\"IL PR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"caption\":\"IL PR News\"},\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/author\\\/il_news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/","og_locale":"th_TH","og_type":"article","og_title":"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning","og_description":"Dr. Tinnaphop Phengpom, Mr. Pongpatai Kitrungloadjanapo [&hellip;]","og_url":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/","og_site_name":"Institute for Innovative Learning","article_published_time":"2023-07-24T05:30:27+00:00","article_modified_time":"2023-07-25T08:03:54+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","type":"image\/jpeg"}],"author":"IL PR News","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#article","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/"},"author":{"name":"IL PR News","@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404"},"headline":"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023.","datePublished":"2023-07-24T05:30:27+00:00","dateModified":"2023-07-25T08:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/"},"wordCount":68,"image":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","keywords":["institute for innovative learning","mahidol university","Suratthani School"],"articleSection":["academic services"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/","url":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/","name":"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023. - Institute for Innovative Learning","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/#website"},"primaryImageOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#primaryimage"},"image":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","datePublished":"2023-07-24T05:30:27+00:00","dateModified":"2023-07-25T08:03:54+00:00","author":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#primaryimage","url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","contentUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-in-the-suratthani-school-july-22-23-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/eng\/"},{"@type":"ListItem","position":2,"name":"Workshop on STEM &amp; Robotics Camp,Suratthani School, July 22-23, 2023."}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/eng\/#website","url":"https:\/\/il.mahidol.ac.th\/eng\/","name":"Institute for Innovative Learning","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404","name":"IL PR News","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","caption":"IL PR News"},"url":"https:\/\/il.mahidol.ac.th\/eng\/author\/il_news\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/07\/innovative_learning_STEM-_-Robotics-Camp_Suratthani-School-001.jpg","jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pb1upD-2FH","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/10273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/comments?post=10273"}],"version-history":[{"count":9,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/10273\/revisions"}],"predecessor-version":[{"id":10423,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/10273\/revisions\/10423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/media\/10347"}],"wp:attachment":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/media?parent=10273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/categories?post=10273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/tags?post=10273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}