{"id":11930,"date":"2023-11-09T12:57:37","date_gmt":"2023-11-09T05:57:37","guid":{"rendered":"https:\/\/il.mahidol.ac.th\/eng\/?p=11930"},"modified":"2023-11-09T12:57:37","modified_gmt":"2023-11-09T05:57:37","slug":"workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023","status":"publish","type":"post","link":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/","title":{"rendered":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023."},"content":{"rendered":"<p>Dr. Tinnapob Phengpom, lecturer Mr. Pongpatai Kitrungloadjanaporn, Mr. Putcharasit Pejaroend, and Mr. Numchoke Kunmunwong, Institute for Innovative Learning, Mahidol University, organized <strong>a workshop on \u201cSTEM &amp; Robotics Camp (Robot War Activity)\u201d<\/strong> for a special classroom grade 8 students on November 4 \u2013 5, 2023 at Thongurai Auditorium 4, Satthasamut School, Samut Songkhram Province.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-11930 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_52.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_52.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_52.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_52-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_03.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_03.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_03.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_03-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_22.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_22.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_22.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_22-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_38.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_38.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_38.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_38-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_15.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_15.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_15.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_15-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_44.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_44.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_44.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_44-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_27.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_27.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_27.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_27-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_09.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_09.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_09.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_09-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_07.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_07.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_07.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_07-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_06.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_06.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_06.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_06-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_04.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_04.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_04.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_04-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_88.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_88.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_88.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_88-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_93.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_93.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_93.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_93-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_162.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_162.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_162.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_162-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_149.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_149.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_149.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_149-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_148.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_148.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_148.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_148-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_138.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_138.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_138.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_138-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg 1200w, https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Dr. Tinnapob Phengpom, lecturer Mr. Pongpatai Kitrunglo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":11948,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":0,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[109,110,271],"class_list":["post-11930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academic-services","tag-institute-for-innovative-learning","tag-mahidol-university","tag-stem-robotics-camp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning\" \/>\n<meta property=\"og:description\" content=\"Dr. Tinnapob Phengpom, lecturer Mr. Pongpatai Kitrunglo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Institute for Innovative Learning\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T05:57:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"IL PR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/\"},\"author\":{\"name\":\"IL PR News\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\"},\"headline\":\"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023.\",\"datePublished\":\"2023-11-09T05:57:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/\"},\"wordCount\":65,\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\",\"keywords\":[\"institute for innovative learning\",\"mahidol university\",\"STEM &amp; Robotics Camp\"],\"articleSection\":[\"academic services\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/\",\"name\":\"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\",\"datePublished\":\"2023-11-09T05:57:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\",\"contentUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/\",\"name\":\"Institute for Innovative Learning\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/#\\\/schema\\\/person\\\/780c07bd864c8f9c50f11679b0ffd404\",\"name\":\"IL PR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"caption\":\"IL PR News\"},\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/eng\\\/author\\\/il_news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/","og_locale":"th_TH","og_type":"article","og_title":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning","og_description":"Dr. Tinnapob Phengpom, lecturer Mr. Pongpatai Kitrunglo [&hellip;]","og_url":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/","og_site_name":"Institute for Innovative Learning","article_published_time":"2023-11-09T05:57:37+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","type":"image\/jpeg"}],"author":"IL PR News","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#article","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/"},"author":{"name":"IL PR News","@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404"},"headline":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023.","datePublished":"2023-11-09T05:57:37+00:00","mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/"},"wordCount":65,"image":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","keywords":["institute for innovative learning","mahidol university","STEM &amp; Robotics Camp"],"articleSection":["academic services"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/","url":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/","name":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023. - Institute for Innovative Learning","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/#website"},"primaryImageOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#primaryimage"},"image":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","datePublished":"2023-11-09T05:57:37+00:00","author":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#primaryimage","url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","contentUrl":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/eng\/workshop-on-stem-robotics-camp-sattha-samut-school-samut-songkhram-november-4-5-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/eng\/"},{"@type":"ListItem","position":2,"name":"Workshop on \u201cSTEM &amp; Robotics Camp\u201d, Sattha Samut School, Samut Songkhram, November 4-5, 2023."}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/eng\/#website","url":"https:\/\/il.mahidol.ac.th\/eng\/","name":"Institute for Innovative Learning","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/eng\/#\/schema\/person\/780c07bd864c8f9c50f11679b0ffd404","name":"IL PR News","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","caption":"IL PR News"},"url":"https:\/\/il.mahidol.ac.th\/eng\/author\/il_news\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/il.mahidol.ac.th\/eng\/wp-content\/uploads\/2023\/11\/innovative_learning_STEMRobotics_Camp_sattha_20231104_179.jpg","jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pb1upD-36q","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/11930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/comments?post=11930"}],"version-history":[{"count":1,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/11930\/revisions"}],"predecessor-version":[{"id":11949,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/posts\/11930\/revisions\/11949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/media\/11948"}],"wp:attachment":[{"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/media?parent=11930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/categories?post=11930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/eng\/wp-json\/wp\/v2\/tags?post=11930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}