{"id":30149,"date":"2023-07-27T10:57:51","date_gmt":"2023-07-27T03:57:51","guid":{"rendered":"https:\/\/il.mahidol.ac.th\/th\/?p=30149"},"modified":"2023-07-27T11:34:23","modified_gmt":"2023-07-27T04:34:23","slug":"innovative_learning_commemoration_rama10_66_thai","status":"publish","type":"post","link":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/","title":{"rendered":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566"},"content":{"rendered":"<p>\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e0a\u0e31\u0e22\u0e40\u0e25\u0e34\u0e28 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1e\u0e23\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e1e\u0e23\u0e30\u0e2a\u0e07\u0e06\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e40\u0e13\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 30 \u0e23\u0e39\u0e1b \u0e16\u0e27\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25 \u0e1e\u0e34\u0e18\u0e35\u0e16\u0e27\u0e32\u0e22\u0e23\u0e32\u0e0a\u0e2a\u0e14\u0e38\u0e14\u0e35\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e1e\u0e34\u0e18\u0e35\u0e16\u0e27\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e0d\u0e32\u0e13\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 71 \u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0f\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e07\u0e23\u0e31\u0e01\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0f\u0e32\u0e04\u0e21 2565 \u0e13 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32<\/p>\n<div id='gallery-1' class='gallery galleryid-30149 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_01.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_01.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_01.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_01-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_02.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_02.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_02.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_02-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_03.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_03.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_03.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_03-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_04.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_04.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_04.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_04-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_05.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_05.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_05.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_05-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_06.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_06.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_06.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_06-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_07.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_07.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_07.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_07-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_08.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_08.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_08.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_08-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_09.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_09.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_09.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_09-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_10.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_10.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_10.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_10-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_11.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_11.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_11.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_11-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_12.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_12.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_12.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_12-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_13.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_13.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_13.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_13-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_14.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_14.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_14.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_14-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_15.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_15.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_15.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_15-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_16.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_16.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_16.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_16-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_17.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_17.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_17.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_17-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_18.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_18.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_18.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_18-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_19.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_19.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_19.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_19-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_20.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_20.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_20.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_20-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_21.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_21.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_21.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_21-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_22.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_22.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_22.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_22-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_23.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_23.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_23.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_23-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_24.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_24.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_24.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_24-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_25.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_25.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_25.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_25-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_26.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_26.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_26.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_26-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_27.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_27.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_27.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_27-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_28.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_28.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_28.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_28-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_29.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_29.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_29.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_29-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_30.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_30.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_30.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_30-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_31.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_31.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_31.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_31-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_32.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_32.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_32.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_32-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_33.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_33.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_33.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_33-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_34.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_34.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_34.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_34-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_35.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_35.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_35.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_35-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_36.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_36.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_36.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_36-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_37.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_37.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_37.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_37-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_38.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_38.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_38.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_38-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_39.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_39.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_39.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_39-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_41.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_41.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_41.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_41-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_42.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_42.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_42.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_42-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_43.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_43.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_43.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_43-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_44.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_44.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_44.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_44-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_45.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_45.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_45.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_45-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_46.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_46.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_46.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_46-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_47.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_47.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_47.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_47-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_48.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_48.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_48.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_48-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_49.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_49.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_49.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_49-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_50.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_50.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_50.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_50-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_51.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_51.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_51.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_51-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_52.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_52.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_52.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_52-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_53.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_53.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_53.jpg 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_53-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":30201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[149,150,973,1166,40,77,288,17],"class_list":["post-30149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity-news","tag-innovative-learning","tag-institute-for-innovative-learning","tag-973","tag-1166","tag-40","tag-77","tag-288","tag-17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:description\" content=\"\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-27T03:57:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T04:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"IL PR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/\"},\"author\":{\"name\":\"IL PR News\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\"},\"headline\":\"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566\",\"datePublished\":\"2023-07-27T03:57:51+00:00\",\"dateModified\":\"2023-07-27T04:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/\"},\"wordCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_commemoration_rama10_66_40.jpg\",\"keywords\":[\"innovative learning\",\"institute for innovative learning\",\"\u0e1e\u0e34\u0e18\u0e35\u0e16\u0e27\u0e32\u0e22\u0e23\u0e32\u0e0a\u0e2a\u0e14\u0e38\u0e14\u0e35\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f\",\"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e1e\u0e23\u0e30\u0e2a\u0e07\u0e06\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e40\u0e13\u0e23\",\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27\",\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\"],\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/\",\"name\":\"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_commemoration_rama10_66_40.jpg\",\"datePublished\":\"2023-07-27T03:57:51+00:00\",\"dateModified\":\"2023-07-27T04:34:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_commemoration_rama10_66_40.jpg\",\"contentUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/innovative_learning_commemoration_rama10_66_40.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_commemoration_rama10_66_thai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\",\"name\":\"IL PR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"caption\":\"IL PR News\"},\"sameAs\":[\"http:\\\/\\\/-\"],\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il_news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_description":"\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25 [&hellip;]","og_url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/","og_site_name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","article_published_time":"2023-07-27T03:57:51+00:00","article_modified_time":"2023-07-27T04:34:23+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","type":"image\/jpeg"}],"author":"IL PR News","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#article","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/"},"author":{"name":"IL PR News","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72"},"headline":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566","datePublished":"2023-07-27T03:57:51+00:00","dateModified":"2023-07-27T04:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/"},"wordCount":5,"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","keywords":["innovative learning","institute for innovative learning","\u0e1e\u0e34\u0e18\u0e35\u0e16\u0e27\u0e32\u0e22\u0e23\u0e32\u0e0a\u0e2a\u0e14\u0e38\u0e14\u0e35\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f","\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e1e\u0e23\u0e30\u0e2a\u0e07\u0e06\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e40\u0e13\u0e23","\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25","\u0e21\u0e2b\u0e34\u0e14\u0e25","\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27","\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49"],"articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/","url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/","name":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#primaryimage"},"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","datePublished":"2023-07-27T03:57:51+00:00","dateModified":"2023-07-27T04:34:23+00:00","author":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#primaryimage","url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","contentUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_commemoration_rama10_66_thai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 28 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566"}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/th\/#website","url":"https:\/\/il.mahidol.ac.th\/th\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72","name":"IL PR News","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","caption":"IL PR News"},"sameAs":["http:\/\/-"],"url":"https:\/\/il.mahidol.ac.th\/th\/author\/il_news\/"}]}},"jetpack_featured_media_url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/07\/innovative_learning_commemoration_rama10_66_40.jpg","views":{"total":32,"cached_at":"","cached_date":1784034413},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/30149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/comments?post=30149"}],"version-history":[{"count":2,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/30149\/revisions"}],"predecessor-version":[{"id":30215,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/30149\/revisions\/30215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media\/30201"}],"wp:attachment":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media?parent=30149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/categories?post=30149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags?post=30149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}