{"id":31841,"date":"2023-08-12T10:01:44","date_gmt":"2023-08-12T03:01:44","guid":{"rendered":"https:\/\/il.mahidol.ac.th\/th\/?p=31841"},"modified":"2023-08-12T10:01:44","modified_gmt":"2023-08-12T03:01:44","slug":"innovative_learning_national-education","status":"publish","type":"post","link":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/","title":{"rendered":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566"},"content":{"rendered":"<p>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e2a\u0e31\u0e08\u0e1e\u0e31\u0e19\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u201d \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e31\u0e49\u0e19 3 \u0e2a\u0e21\u0e28. \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e0d\u0e32\u0e44\u0e17\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32 (\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 BTS \u0e1e\u0e0d\u0e32\u0e44\u0e17) \u0e40\u0e02\u0e15\u0e23\u0e32\u0e0a\u0e40\u0e17\u0e27\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e42\u0e14\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e2a\u0e21\u0e28. \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e10\u0e21\u0e27\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e32\u0e21\u0e2d\u0e31\u0e18\u0e22\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35 \u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566\u201d \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 12 \u0e41\u0e2b\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e2f<\/p>\n<div id='gallery-1' class='gallery galleryid-31841 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_02.gif' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_02.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_02.gif 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_02-768x512.gif 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_01.gif' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_01.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_01.gif 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_01-768x512.gif 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_04.gif' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_04.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_04.gif 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_04-768x512.gif 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05-768x512.gif 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_03.gif' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_03.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_03.gif 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_03-768x512.gif 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e2a\u0e31\u0e08\u0e1e\u0e31\u0e19\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":31846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[46],"tags":[150,40,17],"class_list":["post-31841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-46","tag-institute-for-innovative-learning","tag-40","tag-17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:description\" content=\"\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e2a\u0e31\u0e08\u0e1e\u0e31\u0e19\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-12T03:01:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"IL PR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/\"},\"author\":{\"name\":\"IL PR News\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\"},\"headline\":\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566\",\"datePublished\":\"2023-08-12T03:01:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/\"},\"wordCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/innovative_learning_National-Education_05.gif\",\"keywords\":[\"institute for innovative learning\",\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\"],\"articleSection\":[\"\u0e2d\u0e1a\u0e23\u0e21\\\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/\",\"name\":\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/innovative_learning_National-Education_05.gif\",\"datePublished\":\"2023-08-12T03:01:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#primaryimage\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/innovative_learning_National-Education_05.gif\",\"contentUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/innovative_learning_National-Education_05.gif\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_national-education\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/5d83c85c5c45c4cbb1973ce27c8e0b72\",\"name\":\"IL PR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g\",\"caption\":\"IL PR News\"},\"sameAs\":[\"http:\\\/\\\/-\"],\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il_news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_description":"\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e2a\u0e31\u0e08\u0e1e\u0e31\u0e19\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01 [&hellip;]","og_url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/","og_site_name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","article_published_time":"2023-08-12T03:01:44+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","type":"image\/gif"}],"author":"IL PR News","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#article","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/"},"author":{"name":"IL PR News","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72"},"headline":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566","datePublished":"2023-08-12T03:01:44+00:00","mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/"},"wordCount":5,"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","keywords":["institute for innovative learning","\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25","\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49"],"articleSection":["\u0e2d\u0e1a\u0e23\u0e21\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/","url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/","name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#primaryimage"},"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","datePublished":"2023-08-12T03:01:44+00:00","author":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#primaryimage","url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","contentUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_national-education\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19) \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2566 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566"}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/th\/#website","url":"https:\/\/il.mahidol.ac.th\/th\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/5d83c85c5c45c4cbb1973ce27c8e0b72","name":"IL PR News","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9523ef51b0e230899638bf88a5b17dedf822576b63f237b78b129d95ac27ed?s=96&d=mm&r=g","caption":"IL PR News"},"sameAs":["http:\/\/-"],"url":"https:\/\/il.mahidol.ac.th\/th\/author\/il_news\/"}]}},"jetpack_featured_media_url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2023\/08\/innovative_learning_National-Education_05.gif","views":{"total":13,"cached_at":"","cached_date":1788194676},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/31841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/comments?post=31841"}],"version-history":[{"count":1,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/31841\/revisions"}],"predecessor-version":[{"id":31847,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/31841\/revisions\/31847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media\/31846"}],"wp:attachment":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media?parent=31841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/categories?post=31841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags?post=31841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}