{"id":68547,"date":"2026-04-26T14:15:55","date_gmt":"2026-04-26T07:15:55","guid":{"rendered":"https:\/\/il.mahidol.ac.th\/th\/?p=68547"},"modified":"2026-04-28T14:55:13","modified_gmt":"2026-04-28T07:55:13","slug":"innovative_learning_ai-makers-summer-camp","status":"publish","type":"post","link":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &#038; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569"},"content":{"rendered":"<p>\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &amp; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 \u0e17\u0e35\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e14\u0e23.\u0e1e\u0e07\u0e29\u0e4c\u0e1c\u0e44\u0e17 \u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e32\u0e1e\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e19\u0e33\u0e42\u0e0a\u0e04 \u0e02\u0e38\u0e19\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e27\u0e07\u0e04\u0e4c \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e31\u0e22\u0e40\u0e25\u0e34\u0e28 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1e\u0e23\u0e0a\u0e31\u0e22 \u0e0a\u0e31\u0e49\u0e19 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32<\/p>\n<p>*** \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49 \u0e2b\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e25\u0e1a\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e42\u0e1b\u0e23\u0e14\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e17\u0e35\u0e48 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c 0-2441-9729 Email : ilpdpa@mahidol.ac.th ***<\/p>\n<div id='gallery-1' class='gallery galleryid-68547 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_02.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_02.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_02.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_02-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_02-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_03.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_03.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_03.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_03-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_03-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_04.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_04.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_04.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_04-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_04-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_05.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_05.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_05.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_05-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_05-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_06.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_06.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_06.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_06-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_06-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_07.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_07.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_07.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_07-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_07-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_08.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_08.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_08.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_08-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_08-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_09.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_09.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_09.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_09-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_09-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_10.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_10.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_10.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_10-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_10-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_11.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_11.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_11.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_11-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_11-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_12.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_12.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_12.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_12-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_12-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_13.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_13.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_13.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_13-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_13-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_14.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_14.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_14.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_14-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_14-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_15.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_15.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_15.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_15-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_15-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_16.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_16.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_16.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_16-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_16-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_17.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_17.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_17.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_17-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_17-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_18.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_18.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_18.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_18-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_18-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_19.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_19.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_19.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_19-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_19-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_20.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_20.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_20.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_20-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_20-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_21.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_21.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_21.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_21-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_21-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_22.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_22.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_22.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_22-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_22-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_23.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_23.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_23.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_23-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_23-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_24.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_24.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_24.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_24-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_24-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_25.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_25.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_25.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_25-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_25-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_26.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_26.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_26.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_26-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_26-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_27.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_27.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_27.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_27-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_27-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_28.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_28.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_28.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_28-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_28-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_29.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_29.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_29.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_29-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_29-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_30.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_30.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_30.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_30-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_30-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_31.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_31.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_31.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_31-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_31-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_32.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_32.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_32.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_32-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_32-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_33.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_33.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_33.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_33-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_33-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_34.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_34.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_34.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_34-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_34-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_35.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_35.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_35.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_35-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_35-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_36.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_36.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_36.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_36-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_36-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_37.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_37.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_37.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_37-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_37-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_38.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_38.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_38.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_38-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_38-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_39.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_39.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_39.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_39-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_39-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_40.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_40.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_40.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_40-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_40-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_41.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_41.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_41.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_41-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_41-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_42.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_42.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_42.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_42-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_42-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_43.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_43.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_43.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_43-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_43-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_44.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_44.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_44.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_44-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_44-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_45.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_45.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_45.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_45-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_45-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_46.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_46.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_46.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_46-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_46-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_47.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_47.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_47.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_47-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_47-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_48.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_48.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_48.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_48-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_48-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_49.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_49.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_49.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_49-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_49-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_50.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_50.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_50.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_50-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_50-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_51.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_51.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_51.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_51-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_51-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_52.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_52.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_52.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_52-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_52-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_53.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_53.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_53.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_53-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_53-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_54.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_54.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_54.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_54-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_54-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_55.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_55.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_55.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_55-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_55-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_56.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_56.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_56.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_56-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_56-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_57.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_57.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_57.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_57-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_57-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_58.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_58.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_58.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_58-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_58-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_59.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_59.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_59.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_59-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_59-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_60.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_60.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_60.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_60-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_60-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_61.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_61.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_61.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_61-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_61-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_62.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_62.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_62.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_62-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_62-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_63.webp' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"85\" src=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_63.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_63.webp 1200w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_63-768x512.webp 768w, https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_63-622x420.webp 622w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a [&hellip;]<\/p>\n","protected":false},"author":344,"featured_media":68548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"wpmdr_menu":0,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[46],"tags":[132,149,150,259,95,786,454,40,77,17,1478],"class_list":["post-68547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-46","tag-il","tag-innovative-learning","tag-institute-for-innovative-learning","tag-muil","tag-stem","tag-stem-robotics-camp","tag-454","tag-40","tag-77","tag-17","tag-1478"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &amp; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &amp; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-26T07:15:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T07:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ai Kengsurakarn\u200b\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/\"},\"author\":{\"name\":\"Ai Kengsurakarn\u200b\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/4308fd25c9e20f97936dd42b2ea0c00a\"},\"headline\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &#038; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569\",\"datePublished\":\"2026-04-26T07:15:55+00:00\",\"dateModified\":\"2026-04-28T07:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/\"},\"wordCount\":25,\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/innovative_learning_AI-Makers-Summer-Camp_01.webp\",\"keywords\":[\"IL\",\"innovative learning\",\"institute for innovative learning\",\"MUIL\",\"STEM\",\"STEM &amp; Robotics Camp\",\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\",\"\u0e2a\u0e30\u0e40\u0e15\u0e47\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\"],\"articleSection\":[\"\u0e2d\u0e1a\u0e23\u0e21\\\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/\",\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM & Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/innovative_learning_AI-Makers-Summer-Camp_01.webp\",\"datePublished\":\"2026-04-26T07:15:55+00:00\",\"dateModified\":\"2026-04-28T07:55:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/4308fd25c9e20f97936dd42b2ea0c00a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/innovative_learning_AI-Makers-Summer-Camp_01.webp\",\"contentUrl\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/innovative_learning_AI-Makers-Summer-Camp_01.webp\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/innovative_learning_ai-makers-summer-camp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &#038; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/4308fd25c9e20f97936dd42b2ea0c00a\",\"name\":\"Ai Kengsurakarn\u200b\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/ai-ken_344.jpg\",\"url\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/ai-ken_344.jpg\",\"contentUrl\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/ai-ken_344.jpg\",\"caption\":\"Ai Kengsurakarn\u200b\"},\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/ai-ken\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM & Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM & Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_description":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a [&hellip;]","og_url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/","og_site_name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","article_published_time":"2026-04-26T07:15:55+00:00","article_modified_time":"2026-04-28T07:55:13+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","type":"image\/webp"}],"author":"Ai Kengsurakarn\u200b","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#article","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/"},"author":{"name":"Ai Kengsurakarn\u200b","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/4308fd25c9e20f97936dd42b2ea0c00a"},"headline":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &#038; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569","datePublished":"2026-04-26T07:15:55+00:00","dateModified":"2026-04-28T07:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/"},"wordCount":25,"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","keywords":["IL","innovative learning","institute for innovative learning","MUIL","STEM","STEM &amp; Robotics Camp","\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25","\u0e21\u0e2b\u0e34\u0e14\u0e25","\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49","\u0e2a\u0e30\u0e40\u0e15\u0e47\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32"],"articleSection":["\u0e2d\u0e1a\u0e23\u0e21\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/","url":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/","name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM & Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569 - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#primaryimage"},"image":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#primaryimage"},"thumbnailUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","datePublished":"2026-04-26T07:15:55+00:00","dateModified":"2026-04-28T07:55:13+00:00","author":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/4308fd25c9e20f97936dd42b2ea0c00a"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#primaryimage","url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","contentUrl":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/th\/innovative_learning_ai-makers-summer-camp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u201cSTEM &#038; Robotics Camp\u201d \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cAI Makers Summer Camp\u201d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569"}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/th\/#website","url":"https:\/\/il.mahidol.ac.th\/th\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/4308fd25c9e20f97936dd42b2ea0c00a","name":"Ai Kengsurakarn\u200b","image":{"@type":"ImageObject","inLanguage":"th","@id":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/ai-ken_344.jpg","url":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/ai-ken_344.jpg","contentUrl":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/ai-ken_344.jpg","caption":"Ai Kengsurakarn\u200b"},"url":"https:\/\/il.mahidol.ac.th\/th\/author\/ai-ken\/"}]}},"jetpack_featured_media_url":"https:\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/2026\/04\/innovative_learning_AI-Makers-Summer-Camp_01.webp","views":{"total":8,"cached_at":"","cached_date":1788284951},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/68547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users\/344"}],"replies":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/comments?post=68547"}],"version-history":[{"count":3,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/68547\/revisions"}],"predecessor-version":[{"id":68613,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts\/68547\/revisions\/68613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media\/68548"}],"wp:attachment":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media?parent=68547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/categories?post=68547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags?post=68547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}