{"id":482,"count":1,"description":"","link":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/","name":"moodle","slug":"moodle","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/tag\\\/moodle\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/tag\\\/moodle\\\/\",\"name\":\"moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/tag\\\/moodle\\\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/tag\\\/moodle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"moodle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/","og_locale":"th_TH","og_type":"article","og_title":"moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_url":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/","og_site_name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/","url":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/","name":"moodle Archives - \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#website"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/th\/tag\/moodle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"moodle"}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/th\/#website","url":"https:\/\/il.mahidol.ac.th\/th\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags\/482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/posts?tags=482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}