{"id":1,"name":"IL Admin","url":"","description":"","link":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/","slug":"il-admin","avatar_urls":{"24":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","48":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","96":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png"},"meta":{"jetpack_donation_warning_dismissed":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:url\" content=\"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\" \/>\n<meta property=\"og:image\" content=\"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/\",\"name\":\"IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for IL Admin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/person\\\/d341a34e188dc938c28fd1341df01f61\",\"name\":\"IL Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/il-admin_1.png\",\"url\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/il-admin_1.png\",\"contentUrl\":\"\\\/\\\/il.mahidol.ac.th\\\/th\\\/wp-content\\\/uploads\\\/wpforo\\\/avatars\\\/il-admin_1.png\",\"caption\":\"IL Admin\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/il.mahidol.ac.th\\\/th\\\/author\\\/il-admin\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/","og_locale":"th_TH","og_type":"profile","og_title":"IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_url":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/","og_site_name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","og_image":[{"url":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/","url":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/","name":"IL Admin, Author at \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","isPartOf":{"@id":"https:\/\/il.mahidol.ac.th\/th\/#website"},"breadcrumb":{"@id":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/il.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"Archives for IL Admin"}]},{"@type":"WebSite","@id":"https:\/\/il.mahidol.ac.th\/th\/#website","url":"https:\/\/il.mahidol.ac.th\/th\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/il.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/il.mahidol.ac.th\/th\/#\/schema\/person\/d341a34e188dc938c28fd1341df01f61","name":"IL Admin","image":{"@type":"ImageObject","inLanguage":"th","@id":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","url":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","contentUrl":"\/\/il.mahidol.ac.th\/th\/wp-content\/uploads\/wpforo\/avatars\/il-admin_1.png","caption":"IL Admin"},"mainEntityOfPage":{"@id":"https:\/\/il.mahidol.ac.th\/th\/author\/il-admin\/"}}]}},"elementor_introduction":{"flexbox":true,"rightClick":true,"colorPickerDropping":true},"_links":{"self":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/il.mahidol.ac.th\/th\/wp-json\/wp\/v2\/users"}]}}